{"id":10132,"date":"2025-06-27T08:30:04","date_gmt":"2025-06-27T06:30:04","guid":{"rendered":"https:\/\/www.lanierpharma.com\/?p=10132"},"modified":"2025-12-28T17:09:17","modified_gmt":"2025-12-28T16:09:17","slug":"colageno-tipo-ii","status":"publish","type":"post","link":"https:\/\/dev.lanierpharma.com\/en\/colageno-tipo-ii\/","title":{"rendered":"Una velada cient\u00edfica con sabor gallego"},"content":{"rendered":"<p>El pasado 19 de junio, <strong>Lanier Pharma<\/strong> celebr\u00f3 un evento exclusivo en <a href=\"https:\/\/casalampazasmadrid.com\/\"><strong>Casa Lampazas<\/strong><\/a>, un restaurante de reciente apertura, que destaca por su cocina gallega contempor\u00e1nea y su cuidada atm\u00f3sfera. En una de sus salas, se reunieron profesionales de la medicina de primer nivel para asistir a una ponencia cient\u00edfica centrada en el papel del <strong>col\u00e1geno tipo II<\/strong> en el tratamiento de la artrosis y el abordaje integral del dolor articular.<\/p><p>Como moderador, el <strong>Dr. Enrique Rey D\u00edaz-Rubio<\/strong>, profesor titular de medicina. Catedr\u00e1tico acreditado. Vicedecano de la Facultad de Medicina en la Universidad Complutense y actual miembro del comit\u00e9 cient\u00edfico de Lanier Pharma. Su reputaci\u00f3n en \u00e1reas como la enfermedad inflamatoria intestinal, la motilidad digestiva y los trastornos funcionales le avala como una de las voces m\u00e1s influyentes en el panorama m\u00e9dico actual.<\/p><h2>\u00a0<\/h2><p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/2025\/06\/Colageno-tipo-II-1024x683.jpg\" alt=\"\" width=\"800\" height=\"534\" \/><\/p><h2>Hacia un nuevo enfoque en el tratamiento de la artrosis<\/h2><p>El primero de los ponentes fue el <a href=\"https:\/\/www.instagram.com\/dr.davidlopezcapape\/\"><strong>Dr. David L\u00f3pez Capap\u00e9<\/strong><\/a>, cirujano ortop\u00e9dico y traumat\u00f3logo deportivo, quien recalc\u00f3 la importancia de un abordaje precoz de la artrosis. Destac\u00f3 c\u00f3mo el enfoque de la enfermedad ha ido evolucionando desde tratamientos analg\u00e9sicos o quir\u00fargicos, que se siguen usando en los casos necesarios, hacia tratamientos preventivos o estabilizadores, donde cobran protagonismo, entre otros, los complementos alimenticios, como <strong>Artrinox<\/strong>, que permiten reducir la inflamaci\u00f3n, proteger el cart\u00edlago y mejorar la movilidad, ofreciendo una alternativa eficaz a largo plazo.<\/p><h2>La mol\u00e9cula protagonista: col\u00e1geno tipo II<\/h2><p>El segundo ponente, <strong>Renato Costa<\/strong>, licenciado en Ingenier\u00eda por la Universidad de Tr\u00e1s-os-Montes e Alto Douro (UTAD), especializado en Nutrici\u00f3n Animal, ha orientado su carrera en el \u00e1mbito del desarrollo de negocio internacional de ingredientes funcionales. Desde 2018, responsable global de Marketing y Ventas en Lonza. Este a\u00f1o, RenAto se ha incorporado a Aptissen SA como Director de la Unidad de Negocio de Nutrici\u00f3n. Como experto en UC-II, realiz\u00f3 una exposici\u00f3n t\u00e9cnica y amena sobre las diferencias entre los tipos de col\u00e1geno y la <strong>especificidad del tipo II en el tejido cartilaginoso<\/strong>. Subray\u00f3 que el col\u00e1geno tipo II no desnaturalizado es especialmente eficaz incluso en bajas dosis, al actuar a nivel inmunomodulador. Esta forma espec\u00edfica del col\u00e1geno permite reducir la respuesta inflamatoria autoinmune que degrada el cart\u00edlago en la artrosis.<\/p><p>Renato ilustr\u00f3 su intervenci\u00f3n con un v\u00eddeo cl\u00ednico: el caso de un perro con artrosis severa, grabado antes y despu\u00e9s de un mes de tratamiento con col\u00e1geno UC-II. Las im\u00e1genes hablaron por s\u00ed solas, mostrando una notable recuperaci\u00f3n funcional.<\/p><h2>\u00a0<\/h2><h2>Inteligencia artificial aplicada a la medicina del d\u00eda a d\u00eda<\/h2><p>El <a href=\"https:\/\/www.instagram.com\/borjaocchi\/\"><strong>Dr. Borja Occhi G\u00f3mez<\/strong><\/a>, especialista en cirug\u00eda de mano y cofundador de Red SanitarIA, cerr\u00f3 la ronda de ponencias con un enfoque sorprendente e inspirador. Mostr\u00f3 c\u00f3mo las <strong>herramientas de inteligencia artificial<\/strong> est\u00e1n cambiando la pr\u00e1ctica m\u00e9dica diaria. Comparti\u00f3 casos concretos donde el uso de plataformas como Gamma o Napkin le han permitido optimizar el tiempo de consulta, mejorar la presentaci\u00f3n de casos cl\u00ednicos y agilizar informes m\u00e9dicos.<\/p><h2>Networking con sabor a Galicia<\/h2><p>Tras las ponencias, los asistentes pudieron relajarse y conversar en un ambiente distendido mientras disfrutaban de una cuidada selecci\u00f3n de platos gallegos.<\/p><p>La cena sirvi\u00f3 para reforzar v\u00ednculos entre los profesionales presentes y para compartir experiencias cl\u00ednicas en torno al uso de complementos alimenticios para el tratamiento del dolor articular.<\/p><h2>Una apuesta por la ciencia, la innovaci\u00f3n y el paciente<\/h2><p>El evento fue todo un \u00e9xito, tanto por el alto nivel cient\u00edfico de las ponencias como por el inter\u00e9s que despertaron las soluciones presentadas. El col\u00e1geno tipo II, incluido en <a href=\"https:\/\/dev.lanierpharma.com\/en\/product\/artrinox\/\"><strong>Artrinox<\/strong><\/a>, se consolida como un tratamiento eficaz y seguro para los profesionales que buscan nuevas formas de <strong>mejorar la calidad de vida de los pacientes con artrosis<\/strong>.<a href=\"https:\/\/dev.lanierpharma.com\/en\/product\/artrinox\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/2025\/06\/Colageno-tipo-II-foto2-1024x683.jpg\" alt=\"\" width=\"800\" height=\"534\" \/><\/a>En <strong>Lanier Pharma<\/strong>, seguiremos apostando por la formaci\u00f3n m\u00e9dica, la evidencia cient\u00edfica y los productos innovadores que marcan la diferencia en la pr\u00e1ctica cl\u00ednica diaria, con un objetivo principal; mejorar la calidad de vida de los pacientes.<\/p><p><\/p><!-- \/wp:post-content -->","protected":false},"excerpt":{"rendered":"<p>El pasado 19 de junio celebramos un evento exclusivo donde se reunieron profesionales de la medicina de primer nivel para asistir a una ponencia cient\u00edfica centrada en el papel del col\u00e1geno tipo II en el tratamiento de la artrosis y el abordaje integral del dolor articular. <\/p>","protected":false},"author":1067,"featured_media":10134,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[275,188],"tags":[],"class_list":["post-10132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lanier-pharma","category-salud-articular"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una velada cient\u00edfica con sabor gallego - Lanierpharma<\/title>\n<meta name=\"description\" content=\"\u00bfTe ha pasado alguna vez que, despu\u00e9s de mantener relaciones sexuales, comienzas a notar escozor al orinar, necesidad urgente de ir al ba\u00f1o o molestias en la parte baja del abdomen? Si es as\u00ed, podr\u00edas estar enfrent\u00e1ndote a una cistitis postcoita\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una velada cient\u00edfica con sabor gallego - Lanierpharma\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe ha pasado alguna vez que, despu\u00e9s de mantener relaciones sexuales, comienzas a notar escozor al orinar, necesidad urgente de ir al ba\u00f1o o molestias en la parte baja del abdomen? Si es as\u00ed, podr\u00edas estar enfrent\u00e1ndote a una cistitis postcoita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.lanierpharma.com\/en\/colageno-tipo-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Lanierpharma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lanierpharma\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T06:30:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-28T16:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Colageno-tipo-II-foto1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lanier Pharma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:site\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lanier Pharma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/\"},\"author\":{\"name\":\"Lanier Pharma\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/bedc8513d06d6975d42b212435507660\"},\"headline\":\"Una velada cient\u00edfica con sabor gallego\",\"datePublished\":\"2025-06-27T06:30:04+00:00\",\"dateModified\":\"2025-12-28T16:09:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/\"},\"wordCount\":707,\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Colageno-tipo-II-foto1.jpg\",\"articleSection\":[\"Lanier Pharma\",\"Salud articular\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/\",\"name\":\"Una velada cient\u00edfica con sabor gallego - Lanierpharma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Colageno-tipo-II-foto1.jpg\",\"datePublished\":\"2025-06-27T06:30:04+00:00\",\"dateModified\":\"2025-12-28T16:09:17+00:00\",\"description\":\"\u00bfTe ha pasado alguna vez que, despu\u00e9s de mantener relaciones sexuales, comienzas a notar escozor al orinar, necesidad urgente de ir al ba\u00f1o o molestias en la parte baja del abdomen? Si es as\u00ed, podr\u00edas estar enfrent\u00e1ndote a una cistitis postcoita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Colageno-tipo-II-foto1.jpg\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Colageno-tipo-II-foto1.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/colageno-tipo-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una velada cient\u00edfica con sabor gallego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"name\":\"Lanierpharma\",\"description\":\"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos\",\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.lanierpharma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\",\"name\":\"Lanierpharma\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"width\":567,\"height\":239,\"caption\":\"Lanierpharma\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lanierpharma\",\"https:\\\/\\\/x.com\\\/LanierPharma\",\"https:\\\/\\\/www.instagram.com\\\/lanier_pharma\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/bedc8513d06d6975d42b212435507660\",\"name\":\"Lanier Pharma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23063199bcaff9e11a33a91cb2e9b5f286a7f7c6700bdb01c183be3581350f28?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23063199bcaff9e11a33a91cb2e9b5f286a7f7c6700bdb01c183be3581350f28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23063199bcaff9e11a33a91cb2e9b5f286a7f7c6700bdb01c183be3581350f28?s=96&d=mm&r=g\",\"caption\":\"Lanier Pharma\"},\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/en\\\/author\\\/marta-sanz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una velada cient\u00edfica con sabor gallego - Lanierpharma","description":"\u00bfTe ha pasado alguna vez que, despu\u00e9s de mantener relaciones sexuales, comienzas a notar escozor al orinar, necesidad urgente de ir al ba\u00f1o o molestias en la parte baja del abdomen? Si es as\u00ed, podr\u00edas estar enfrent\u00e1ndote a una cistitis postcoita","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Una velada cient\u00edfica con sabor gallego - Lanierpharma","og_description":"\u00bfTe ha pasado alguna vez que, despu\u00e9s de mantener relaciones sexuales, comienzas a notar escozor al orinar, necesidad urgente de ir al ba\u00f1o o molestias en la parte baja del abdomen? Si es as\u00ed, podr\u00edas estar enfrent\u00e1ndote a una cistitis postcoita","og_url":"https:\/\/dev.lanierpharma.com\/en\/colageno-tipo-ii\/","og_site_name":"Lanierpharma","article_publisher":"https:\/\/www.facebook.com\/lanierpharma","article_published_time":"2025-06-27T06:30:04+00:00","article_modified_time":"2025-12-28T16:09:17+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Colageno-tipo-II-foto1.jpg","type":"image\/jpeg"}],"author":"Lanier Pharma","twitter_card":"summary_large_image","twitter_creator":"@LanierPharma","twitter_site":"@LanierPharma","twitter_misc":{"Written by":"Lanier Pharma","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/#article","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/"},"author":{"name":"Lanier Pharma","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/bedc8513d06d6975d42b212435507660"},"headline":"Una velada cient\u00edfica con sabor gallego","datePublished":"2025-06-27T06:30:04+00:00","dateModified":"2025-12-28T16:09:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/"},"wordCount":707,"publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Colageno-tipo-II-foto1.jpg","articleSection":["Lanier Pharma","Salud articular"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/","url":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/","name":"Una velada cient\u00edfica con sabor gallego - Lanierpharma","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/#primaryimage"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Colageno-tipo-II-foto1.jpg","datePublished":"2025-06-27T06:30:04+00:00","dateModified":"2025-12-28T16:09:17+00:00","description":"\u00bfTe ha pasado alguna vez que, despu\u00e9s de mantener relaciones sexuales, comienzas a notar escozor al orinar, necesidad urgente de ir al ba\u00f1o o molestias en la parte baja del abdomen? Si es as\u00ed, podr\u00edas estar enfrent\u00e1ndote a una cistitis postcoita","breadcrumb":{"@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/#primaryimage","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Colageno-tipo-II-foto1.jpg","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Colageno-tipo-II-foto1.jpg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/dev.lanierpharma.com\/colageno-tipo-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.lanierpharma.com\/"},{"@type":"ListItem","position":2,"name":"Una velada cient\u00edfica con sabor gallego"}]},{"@type":"WebSite","@id":"https:\/\/dev.lanierpharma.com\/#website","url":"https:\/\/dev.lanierpharma.com\/","name":"Lanierpharma","description":"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos","publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.lanierpharma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dev.lanierpharma.com\/#organization","name":"Lanierpharma","url":"https:\/\/dev.lanierpharma.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","width":567,"height":239,"caption":"Lanierpharma"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lanierpharma","https:\/\/x.com\/LanierPharma","https:\/\/www.instagram.com\/lanier_pharma\/"]},{"@type":"Person","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/bedc8513d06d6975d42b212435507660","name":"Lanier Pharma","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/23063199bcaff9e11a33a91cb2e9b5f286a7f7c6700bdb01c183be3581350f28?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23063199bcaff9e11a33a91cb2e9b5f286a7f7c6700bdb01c183be3581350f28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23063199bcaff9e11a33a91cb2e9b5f286a7f7c6700bdb01c183be3581350f28?s=96&d=mm&r=g","caption":"Lanier Pharma"},"url":"https:\/\/dev.lanierpharma.com\/en\/author\/marta-sanz\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/10132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/users\/1067"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/comments?post=10132"}],"version-history":[{"count":1,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/10132\/revisions"}],"predecessor-version":[{"id":11638,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/10132\/revisions\/11638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media\/10134"}],"wp:attachment":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media?parent=10132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/categories?post=10132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/tags?post=10132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}