{"id":3362,"date":"2023-11-08T09:07:00","date_gmt":"2023-11-08T08:07:00","guid":{"rendered":"https:\/\/www.lanierpharma.com\/?p=3362"},"modified":"2023-11-08T09:07:00","modified_gmt":"2023-11-08T08:07:00","slug":"otono-influencia-estado-animo","status":"publish","type":"post","link":"https:\/\/dev.lanierpharma.com\/en\/otono-influencia-estado-animo\/","title":{"rendered":"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo"},"content":{"rendered":"<p>\n\n\n<\/p>\n<p>El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores pueden afectar nuestro <strong>estado de \u00e1nimo<\/strong> y hacernos sentir m\u00e1s <strong>melanc\u00f3licos o deca\u00eddos<\/strong>. En este art\u00edculo, exploraremos las razones detr\u00e1s de esta disminuci\u00f3n en el \u00e1nimo y te brindaremos <a href=\"https:\/\/dev.lanierpharma.com\/en\/\">consejos pr\u00e1cticos <\/a>para evitarlo.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<h2 class=\"wp-block-heading\">Cambios en las horas de luz<\/h2>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>El oto\u00f1o se caracteriza por d\u00edas m\u00e1s cortos y menos luz solar. La<strong> falta de exposici\u00f3n a la luz natural puede afectar a nuestros niveles de serotonina<\/strong>, una sustancia qu\u00edmica en el cerebro que influye en nuestro estado de \u00e1nimo. Esa falta de exposici\u00f3n a los rayos solares, hace que <strong>nuestros niveles de vitamina D bajen dr\u00e1sticamente<\/strong>. Afortunadamente, puedes contrarrestar esto, aprovechando al m\u00e1ximo la luz natural durante el d\u00eda. Pasea o disfruta de actividades al aire libre. Si el d\u00eda est\u00e1 desapacible, bastar\u00e1 con que tomes el sol a trav\u00e9s de una ventana, para marcar una gran diferencia.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p><strong>Temperaturas m\u00e1s bajas<\/strong><\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>\u00a0El descenso de las temperaturas puede hacer que nos sintamos m\u00e1s cansados y con menos energ\u00eda. Para evitarlo, nada mejor que mantenerse activos f\u00edsicamente. Realiza <strong>ejercicio regularmente<\/strong>, incluso si es en interiores, as\u00ed <strong>aumentar\u00e1s los niveles de endorfinas<\/strong>, las llamadas \u00abhormonas de la felicidad\u00bb, mejorando de inmediato tu estado de \u00e1nimo.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p><strong>Vuelta a la rutina<\/strong>.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Despu\u00e9s de las vacaciones de verano, muchas personas experimentan una sensaci\u00f3n de <strong>nostalgia y tristeza al regresar a la rutina diaria<\/strong>. Para contrarrestar esto, es importante que <strong>establezcas nuevas metas y actividades que te motiven<\/strong>. Planifica actividades sociales, aprende algo nuevo o embarcarte en un proyecto personal para mantenerte enfocado y entusiasta durante el oto\u00f1o.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<h2 class=\"wp-block-heading\">Consejos para evitar la melancol\u00eda estacional<\/h2>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p><strong>Cu\u00eddate y m\u00edmate<\/strong>.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Mant\u00e9n una<strong> alimentaci\u00f3n equilibrada, duerme lo suficiente y practica t\u00e9cnicas de relajaci\u00f3n<\/strong>, como la meditaci\u00f3n o el yoga; esto te ayudar\u00e1 a mantener un equilibrio emocional y prevenir la melancol\u00eda estacional.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Intenta consumir alimentos ricos en tript\u00f3fano, un amino\u00e1cido que <strong>favorece la producci\u00f3n de serotonina<\/strong>. Algunos ejemplos son los pl\u00e1tanos, los frutos secos, los huevos, el pescado azul o el chocolate negro.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Mant\u00e9n <strong>lazos sociales positivos.<\/strong><\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>El contacto social es crucial para nuestro <strong>bienestar emocional<\/strong>. Durante el oto\u00f1o, tendemos a quedarnos m\u00e1s en casa y aislarnos un poco del mundo que nos rodea.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Busca actividades sociales que te hagan sentir bien como organizar reuniones con amigos, participar en grupos de inter\u00e9s o realiza actividades solidarias.\u00a0<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Adem\u00e1s el oto\u00f1o tambi\u00e9n tiene sus ventajas: es una \u00e9poca ideal para disfrutar de un buen <strong>libro, una pel\u00edcula, una serie, un juego<\/strong> o una afici\u00f3n que nos guste. Estas actividades nos distraen de los problemas, nos entretienen y nos hacen sentir bien. Si, adem\u00e1s, haces estas actividades en buena compa\u00f1\u00eda, el beneficio ser\u00e1 doble.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p><strong>Suplem\u00e9ntate para levantar el \u00e1nimo<\/strong>.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Si sigues los anteriores consejos y a\u00fan no sientes el estado positivo que necesitas, <strong>pide consejo profesional<\/strong>. Es posible que te manden alg\u00fan suplemento que te ayude a llevar el cambio estacional de forma natural y sana; con <strong>vitaminas D y C<\/strong>, <strong>el complejo B, tript\u00f3fano<\/strong> y\/o melatonina.<\/p>\n<p>\n\n\n<\/p>\n<p>\n\n\n<\/p>\n<p>Desde<a href=\"https:\/\/dev.lanierpharma.com\/en\/contacto\/\"><strong> Lanier Pharma<\/strong><\/a>, tu laboratorio de suplementaci\u00f3n natural, te ofrecemos <strong>Trineurol<\/strong>,\u00a0 con <strong>\u00c1cido Alfa lipoico, Tript\u00f3fano, Acetil L-Carnitina y vitaminas del complejo B, C y D.<\/strong> Este\u00a0 producto no solo te ayuda a <strong>mantener tu estado de \u00e1nimo positivo<\/strong> sino que mantiene el estado cognitivo\u00a0 y<strong> reduce\u00a0 el dolor neurop\u00e1tico<\/strong>.<\/p>\n<p>\n\n\n<\/p>","protected":false},"excerpt":{"rendered":"<p>El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores pueden afectar nuestro estado de \u00e1nimo y hacernos sentir m\u00e1s melanc\u00f3licos o deca\u00eddos. En este art\u00edculo, exploraremos las razones detr\u00e1s de esta disminuci\u00f3n en el \u00e1nimo y [&hellip;]<\/p>\n","protected":false},"author":1291,"featured_media":3363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[456],"tags":[490,492,285],"class_list":["post-3362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-estado-de-animo","tag-otono","tag-trineurol"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo - Lanierpharma<\/title>\n<meta name=\"description\" content=\"El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo - Lanierpharma\" \/>\n<meta property=\"og:description\" content=\"El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.lanierpharma.com\/en\/otono-influencia-estado-animo\/\" \/>\n<meta property=\"og:site_name\" content=\"Lanierpharma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lanierpharma\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T08:07:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:site\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/\"},\"author\":{\"name\":\"redaccion\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/e0112d4efe5220eb883062a02bc83a7e\"},\"headline\":\"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo\",\"datePublished\":\"2023-11-08T08:07:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/\"},\"wordCount\":633,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier.jpg\",\"keywords\":[\"estado de \u00e1nimo\",\"oto\u00f1o\",\"trineurol\"],\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/\",\"name\":\"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo - Lanierpharma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier.jpg\",\"datePublished\":\"2023-11-08T08:07:00+00:00\",\"description\":\"El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier.jpg\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/otono-influencia-estado-animo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"name\":\"Lanierpharma\",\"description\":\"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos\",\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.lanierpharma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\",\"name\":\"Lanierpharma\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"width\":567,\"height\":239,\"caption\":\"Lanierpharma\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lanierpharma\",\"https:\\\/\\\/x.com\\\/LanierPharma\",\"https:\\\/\\\/www.instagram.com\\\/lanier_pharma\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/e0112d4efe5220eb883062a02bc83a7e\",\"name\":\"redaccion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"caption\":\"redaccion\"},\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/en\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo - Lanierpharma","description":"El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo - Lanierpharma","og_description":"El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores","og_url":"https:\/\/dev.lanierpharma.com\/en\/otono-influencia-estado-animo\/","og_site_name":"Lanierpharma","article_publisher":"https:\/\/www.facebook.com\/lanierpharma","article_published_time":"2023-11-08T08:07:00+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier.jpg","type":"image\/jpeg"}],"author":"redaccion","twitter_card":"summary_large_image","twitter_creator":"@LanierPharma","twitter_site":"@LanierPharma","twitter_misc":{"Written by":"redaccion","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#article","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/"},"author":{"name":"redaccion","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/e0112d4efe5220eb883062a02bc83a7e"},"headline":"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo","datePublished":"2023-11-08T08:07:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/"},"wordCount":633,"commentCount":0,"publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier.jpg","keywords":["estado de \u00e1nimo","oto\u00f1o","trineurol"],"articleSection":["Sin categor\u00eda"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/","url":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/","name":"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo - Lanierpharma","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#primaryimage"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier.jpg","datePublished":"2023-11-08T08:07:00+00:00","description":"El oto\u00f1o es una estaci\u00f3n que trae consigo cambios en las horas de luz, temperaturas m\u00e1s bajas y una vuelta a la rutina tras el verano. Estos factores","breadcrumb":{"@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#primaryimage","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier.jpg","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier.jpg","width":1920,"height":1280,"caption":"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.lanierpharma.com\/otono-influencia-estado-animo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.lanierpharma.com\/"},{"@type":"ListItem","position":2,"name":"El oto\u00f1o y su influencia en nuestro estado de \u00e1nimo"}]},{"@type":"WebSite","@id":"https:\/\/dev.lanierpharma.com\/#website","url":"https:\/\/dev.lanierpharma.com\/","name":"Lanierpharma","description":"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos","publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.lanierpharma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dev.lanierpharma.com\/#organization","name":"Lanierpharma","url":"https:\/\/dev.lanierpharma.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","width":567,"height":239,"caption":"Lanierpharma"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lanierpharma","https:\/\/x.com\/LanierPharma","https:\/\/www.instagram.com\/lanier_pharma\/"]},{"@type":"Person","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/e0112d4efe5220eb883062a02bc83a7e","name":"redaccion","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","caption":"redaccion"},"url":"https:\/\/dev.lanierpharma.com\/en\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/3362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/users\/1291"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/comments?post=3362"}],"version-history":[{"count":0,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/3362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media\/3363"}],"wp:attachment":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media?parent=3362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/categories?post=3362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/tags?post=3362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}