{"id":4275,"date":"2023-12-20T09:25:00","date_gmt":"2023-12-20T08:25:00","guid":{"rendered":"https:\/\/www.lanierpharma.com\/?p=4275"},"modified":"2025-12-28T17:09:19","modified_gmt":"2025-12-28T16:09:19","slug":"depresion-navidad","status":"publish","type":"post","link":"https:\/\/dev.lanierpharma.com\/en\/depresion-navidad\/","title":{"rendered":"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os"},"content":{"rendered":"<p>Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares y esp\u00edritu festivo; pero tambi\u00e9n tienen un lado oscuro del que a menudo nos olvidamos. La compra de regalos, la elaboraci\u00f3n de men\u00fas especiales y el acomodo de nuestros invitados pueden causarnos estr\u00e9s. Adem\u00e1s, para muchas es un per\u00edodo de tristeza, a\u00f1oranza y apat\u00eda. Son fechas emotivas donde podemos sentimos m\u00e1s la ausencia de nuestros seres queridos.<\/p>\n\n\n\n<p>En <a href=\"https:\/\/dev.lanierpharma.com\/en\/\">Lanier Pharma<\/a> queremos ofrecerte estrategias pr\u00e1cticas y sencillas para ayudarte a pasar estas fechas sin estr\u00e9s y con buen estado de \u00e1nimo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las Navidades no son un anuncio de la TV<\/h2>\n\n\n\n<p>Las expectativas sociales, las demandas financieras y la presi\u00f3n para sentirse alegre pueden contribuir a provocarnos sentimientos abrumadores. Sobre todo si eres una persona altamente sensible, la carga emotiva de estas fechas puede desbordarte, haciendo que te sea <strong>dif\u00edcil afrontar tus sentimientos<\/strong>. Por eso vamos a analizar contigo las <strong>principales causas que nos generan estr\u00e9s y tristeza <\/strong>de estas fechas para poder combatirlas con \u00e9xito.<\/p>\n\n\n\n<p><strong>Expectativas poco realistas<\/strong>. La presi\u00f3n social y las expectativas poco realistas sobre c\u00f3mo deber\u00eda ser la Navidad pueden generar estr\u00e9s y ansiedad. El omnipresente marketing y la publicidad que generan estas fiestas, van ejercitando una presi\u00f3n silenciosa en todos nosotros que termina por pasarnos factura.<\/p>\n\n\n\n<p>Soluci\u00f3n: Establece expectativas realistas. La navidad no es c\u00f3mo la pintan los anuncios de TV. Reconoce que <strong>la perfecci\u00f3n no es alcanzable<\/strong> y que cada celebraci\u00f3n tiene sus altibajos. <strong>Enf\u00f3cate en el tiempo de calidad<\/strong>, no en la perfecci\u00f3n. Prioriza el<strong> tiempo de calidad con tus seres queridos<\/strong> en lugar de preocuparte por la presentaci\u00f3n impecable de las festividades.<\/p>\n\n\n\n<p><strong>Presiones financieras<\/strong>. Estas fechas son sin duda las m\u00e1s consumistas del a\u00f1o. Tenemos que afrontar muchos <strong>gastos extra como los regalos, las cenas de trabajo<\/strong>, familiares\u2026 Todos estos gastos adicionales pueden generar estr\u00e9s financiero.<\/p>\n\n\n\n<p>Soluci\u00f3n: <strong>Establece un presupuesto<\/strong>. C\u00ed\u00f1ete a un presupuesto razonable para regalos, comidas y entretenimiento.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/2023\/12\/Lanier_pharma_1-1-1024x682.jpg\" alt=\"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os\" class=\"wp-image-4277\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La navidad no es solo alegr\u00eda, tambi\u00e9n se siente tristeza por los seres queridos que faltan<\/h2>\n\n\n\n<p><strong>Soledad.<\/strong> Para algunas personas, la \u00e9poca navide\u00f1a <strong>puede acentuar la sensaci\u00f3n de soledad<\/strong>, especialmente si no tienen la oportunidad de reunirse con familiares o amigos.<\/p>\n\n\n\n<p>Soluci\u00f3n:<strong> Conecta con los dem\u00e1s<\/strong>. Si no tienes la oportunidad o las ganas de pasar tu tiempo de ocio en familia, comp\u00e1rtelo con quien realmente te apetece: personas afines, amigos, vecinos, etc. Hay muchas oportunidades para conectarte con otros, ya sea a trav\u00e9s de eventos comunitarios, voluntariado o la participaci\u00f3n en actividades grupales<\/p>\n\n\n\n<p><strong>Recuerdos dolorosos<\/strong>. La Navidad suele evocar recuerdos dolorosos, sobre todo asociados a p\u00e9rdidas afectivas. Esto aumenta dr\u00e1sticamente nuestra sensaci\u00f3n de tristeza, p\u00e9rdida y depresi\u00f3n.<\/p>\n\n\n\n<p>Soluci\u00f3n: No te olvides de <strong>cuidar de ti mismo<\/strong>. En estos d\u00edas ajetreados, acu\u00e9rdate de dedicar parte de tu tiempo a cuidar tu bienestar f\u00edsico y emocional. Busca actividades que te brinden alegr\u00eda, calma y pongan las cosas en perspectiva.<\/p>\n\n\n\n<p><strong>Practica la gratitud y la solidaridad. <\/strong>Enf\u00f3cate en las cosas buenas que tienes en la vida, cosas por las que est\u00e1s agradecido y reconoce las peque\u00f1as alegr\u00edas que la temporada navide\u00f1a te regala.<\/p>\n\n\n\n<p>Encuentra significado en la temporada navide\u00f1a, participando en actividades que te aporten, ya sea a trav\u00e9s de la religi\u00f3n, la espiritualidad o el servicio a los dem\u00e1s.<\/p>\n\n\n\n<p><strong>Busca apoyo si lo necesitas<\/strong>. Si te sientes abrumado, busca el apoyo de amigos, familiares o profesionales de la salud mental. No te sientas mal por pedir ayuda si la necesitas.<\/p>\n\n\n\n<p><strong>Fatiga y agotamiento<\/strong>. El ajetreo y el bullicio de estas celebraciones unidas a nuestros quehaceres del d\u00eda a d\u00eda, suele causarnos fatiga, agotamiento y apat\u00eda.&nbsp;<\/p>\n\n\n\n<p>Soluci\u00f3n: <strong>Establece l\u00edmites<\/strong>. Aprende a decir \u201cno\u201d de manera respetuosa si sientes que est\u00e1s asumiendo demasiadas responsabilidades. Planifica todo lo que puedas con <strong>anticipaci\u00f3n<\/strong>. Siempre que sea posible, organiza tus compromisos y responsabilidades con anticipaci\u00f3n para reducir el estr\u00e9s de \u00faltima. Si los planes se tuercen, no te estreses y d\u00e9jate llevar, siempre hay una soluci\u00f3n si estamos en calma.<\/p>\n\n\n\n<p>Y si necesitas un extra de ayuda, <strong><a href=\"https:\/\/dev.lanierpharma.com\/en\/product\/trineurol\/\">Trineurol<\/a><\/strong>, un medicamento natural muy eficaz para tu sistema nervioso y tu estado de \u00e1nimo. Su potente sinergia con tript\u00f3fano, vitaminas del grupo B, vitamina D, \u00e1cido alfa lipoico y Acetil-Carnitina, contribuye al mantenimiento de un estado de \u00e1nimo saludable mientras cuida eficazmente del sistema nervioso.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares y esp\u00edritu festivo; pero tambi\u00e9n tienen un lado oscuro del que a menudo nos olvidamos. La compra de regalos, la elaboraci\u00f3n de men\u00fas especiales y el acomodo de nuestros invitados pueden causarnos estr\u00e9s. Adem\u00e1s, para muchas es [&hellip;]<\/p>\n","protected":false},"author":1291,"featured_media":4276,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[456],"tags":[512,514,216],"class_list":["post-4275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-depresion","tag-navidad","tag-suplementos-nutricionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os - Lanierpharma<\/title>\n<meta name=\"description\" content=\"Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os - Lanierpharma\" \/>\n<meta property=\"og:description\" content=\"Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.lanierpharma.com\/en\/depresion-navidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Lanierpharma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lanierpharma\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-20T08:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-28T16:09:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_pharma-1-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:site\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/\"},\"author\":{\"name\":\"redaccion\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/e0112d4efe5220eb883062a02bc83a7e\"},\"headline\":\"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os\",\"datePublished\":\"2023-12-20T08:25:00+00:00\",\"dateModified\":\"2025-12-28T16:09:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/\"},\"wordCount\":802,\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_pharma-1-4.jpg\",\"keywords\":[\"depresi\u00f3n\",\"navidad\",\"suplementos nutricionales\"],\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/\",\"name\":\"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os - Lanierpharma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_pharma-1-4.jpg\",\"datePublished\":\"2023-12-20T08:25:00+00:00\",\"dateModified\":\"2025-12-28T16:09:19+00:00\",\"description\":\"Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_pharma-1-4.jpg\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_pharma-1-4.jpg\",\"width\":1280,\"height\":851,\"caption\":\"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/depresion-navidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"name\":\"Lanierpharma\",\"description\":\"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos\",\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.lanierpharma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\",\"name\":\"Lanierpharma\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"width\":567,\"height\":239,\"caption\":\"Lanierpharma\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lanierpharma\",\"https:\\\/\\\/x.com\\\/LanierPharma\",\"https:\\\/\\\/www.instagram.com\\\/lanier_pharma\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/e0112d4efe5220eb883062a02bc83a7e\",\"name\":\"redaccion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"caption\":\"redaccion\"},\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/en\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os - Lanierpharma","description":"Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os - Lanierpharma","og_description":"Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares...","og_url":"https:\/\/dev.lanierpharma.com\/en\/depresion-navidad\/","og_site_name":"Lanierpharma","article_publisher":"https:\/\/www.facebook.com\/lanierpharma","article_published_time":"2023-12-20T08:25:00+00:00","article_modified_time":"2025-12-28T16:09:19+00:00","og_image":[{"width":1280,"height":851,"url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_pharma-1-4.jpg","type":"image\/jpeg"}],"author":"redaccion","twitter_card":"summary_large_image","twitter_creator":"@LanierPharma","twitter_site":"@LanierPharma","twitter_misc":{"Written by":"redaccion","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/#article","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/"},"author":{"name":"redaccion","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/e0112d4efe5220eb883062a02bc83a7e"},"headline":"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os","datePublished":"2023-12-20T08:25:00+00:00","dateModified":"2025-12-28T16:09:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/"},"wordCount":802,"publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_pharma-1-4.jpg","keywords":["depresi\u00f3n","navidad","suplementos nutricionales"],"articleSection":["Sin categor\u00eda"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/","url":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/","name":"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os - Lanierpharma","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/#primaryimage"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_pharma-1-4.jpg","datePublished":"2023-12-20T08:25:00+00:00","dateModified":"2025-12-28T16:09:19+00:00","description":"Pocas \u00e9pocas son tan entra\u00f1ables y emotivas como las Navidades. Estas fechas est\u00e1n llenas de celebraciones, encuentros familiares...","breadcrumb":{"@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.lanierpharma.com\/depresion-navidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/#primaryimage","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_pharma-1-4.jpg","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_pharma-1-4.jpg","width":1280,"height":851,"caption":"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.lanierpharma.com\/depresion-navidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.lanierpharma.com\/"},{"@type":"ListItem","position":2,"name":"Depresi\u00f3n, estr\u00e9s y apat\u00eda: evita la visita de estos Grinchs navide\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/dev.lanierpharma.com\/#website","url":"https:\/\/dev.lanierpharma.com\/","name":"Lanierpharma","description":"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos","publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.lanierpharma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dev.lanierpharma.com\/#organization","name":"Lanierpharma","url":"https:\/\/dev.lanierpharma.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","width":567,"height":239,"caption":"Lanierpharma"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lanierpharma","https:\/\/x.com\/LanierPharma","https:\/\/www.instagram.com\/lanier_pharma\/"]},{"@type":"Person","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/e0112d4efe5220eb883062a02bc83a7e","name":"redaccion","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","caption":"redaccion"},"url":"https:\/\/dev.lanierpharma.com\/en\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/4275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/users\/1291"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/comments?post=4275"}],"version-history":[{"count":1,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/4275\/revisions"}],"predecessor-version":[{"id":11654,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/4275\/revisions\/11654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media\/4276"}],"wp:attachment":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media?parent=4275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/categories?post=4275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/tags?post=4275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}