{"id":4585,"date":"2024-01-24T10:06:00","date_gmt":"2024-01-24T09:06:00","guid":{"rendered":"https:\/\/www.lanierpharma.com\/?p=4585"},"modified":"2025-12-28T17:09:17","modified_gmt":"2025-12-28T16:09:17","slug":"tips-mejorar-calidad-vida","status":"publish","type":"post","link":"https:\/\/dev.lanierpharma.com\/en\/tips-mejorar-calidad-vida\/","title":{"rendered":"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida"},"content":{"rendered":"<p>Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es<strong> mejorar nuestra calidad de vida<\/strong>. Desde<strong> <\/strong><a href=\"https:\/\/dev.lanierpharma.com\/en\/\"><strong>Lanier Pharma<\/strong><\/a> te vamos a dar algunos consejos para que cuidarte sea f\u00e1cil y placentero.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El primer paso es establecer una rutina de h\u00e1bitos saludables<\/h2>\n\n\n\n<p>Vete implementando los<strong> h\u00e1bitos saludables<\/strong> a tu propio ritmo y sin agobiarte. As\u00ed conseguir\u00e1s que el proceso sea real y duradero y no los abandones enseguida. Lo importante es <strong>establecer unos h\u00e1bitos saludables y mantenerlos en el tiempo <\/strong>para que se vuelvan parte de tus rutinas diarias. Esto te llevar\u00e1 a <strong>mejorar tu salud y bienestar <\/strong>de forma efectiva.<\/p>\n\n\n\n<p>Antes de implementar esas nuevas medidas saludables, quiz\u00e1s debas abandonar otras que no lo son tanto. <strong>Deja el tabaco, la ingesta excesiva de alcohol<\/strong>, y cualquier otro h\u00e1bito que tengas que te impida tener el estado de salud f\u00edsica y mental que deseas. Solo con esta primera medida tu salud va a mejorar sensiblemente.<\/p>\n\n\n\n<p>Es hora de<strong> construir las bases para una salud fuerte y duradera<\/strong>. T\u00f3mate un tiempo para pensar en tus objetivos reales, la mejor manera de conseguirlos y c\u00f3mo puedes hacer que te sean f\u00e1ciles y placenteros.<strong> Ordena tu vida y tu entorno<\/strong>, esto te permitir\u00e1 incluir unos h\u00e1bitos saludables de forma continuada y eficaz.<\/p>\n\n\n\n<p><strong>Mantente en un peso saludable<\/strong>: El sobrepeso y la obesidad aumentan el riesgo de desarrollar enfermedades metab\u00f3licas, enfermedades card\u00edacas y algunos tipos de c\u00e1ncer.<\/p>\n\n\n\n<p><strong>Cuida tu sue\u00f1o<\/strong>. Est\u00e1 demostrado que la <strong>cantidad y calidad de nuestras horas de sue\u00f1o <\/strong>influyen directamente en nuestra salud f\u00edsica y mental.<\/p>\n\n\n\n<p>No descuides tu paz mental. En un mundo cada vez m\u00e1s estresado, cuidar <strong>nuestro bienestar emocional<\/strong> se ha convertido en un pilar b\u00e1sico. Hay miles de formas de hacerlo: medita, pasa tiempo con amigos o familiares, ded\u00edcate a proyectos sociales que te llenen, disfruta con tus hobbies\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/2024\/01\/Lanier_Pharma_1-2-1024x683.jpg\" alt=\"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida\" class=\"wp-image-4588\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Cuidarnos debe ser f\u00e1cil y placentero<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Alim\u00e9ntate de forma sana pero sabrosa<\/strong><\/h3>\n\n\n\n<p>Una <strong>alimentaci\u00f3n saludable<\/strong> es esencial para mantener una buena salud f\u00edsica y mental. La Dieta debe ser equilibrada y variada, incluyendo todos los grupos alimenticios. No debemos renunciar a ning\u00fan alimento, solo ingerirlos en la proporci\u00f3n adecuada, <strong>priorizando verduras, carnes magras y frutas \u00e1cidas<\/strong>. Seguidos de cereales en su versi\u00f3n integral, legumbres y l\u00e1cteos. Y consumiendo de forma puntual alimentos ricos en grasas y az\u00facares. Es importante evitar en lo posible el consumo de alimentos ultraprocesados, az\u00facares a\u00f1adidos y grasas saturadas.<\/p>\n\n\n\n<p>Incluye recetas sabrosas, sorprendentes y variadas para que comer sano sea todo un placer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mu\u00e9vete todos los d\u00edas<\/h3>\n\n\n\n<p>El <strong>ejercicio f\u00edsico regular <\/strong>es un puntal b\u00e1sico para mantener un buen estado de salud. La pr\u00e1ctica f\u00edsica no solo nos ayuda a mantener un peso saludable. Tambi\u00e9n, fortalece nuestros m\u00fasculos y los huesos, nos mantiene \u00e1giles y mejora enormemente nuestro estado de \u00e1nimo.<\/p>\n\n\n\n<p>La recomendaci\u00f3n generalizada es realizar <strong>al menos 30 minutos de actividad f\u00edsica moderada al menos 5 d\u00edas a la semana.<\/strong> En esa categor\u00eda se incluyen el yoga, el baile, la nataci\u00f3n, el pilates. Elige el que m\u00e1s te guste y se ajuste a tu estado f\u00edsico.<\/p>\n\n\n\n<p>Tambi\u00e9n intenta<strong> caminar diariamente al menos otra media hora<\/strong> o haz una media de unos <strong>10.000 pasos<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ay\u00fadate con una buena suplementaci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Los <strong>suplementos alimenticios<\/strong> son una forma perfecta para complementar tu dieta y obtener los nutrientes que te faltan. Asimismo, son tus grandes aliados para mejorar tu <strong>calidad de vida<\/strong>.<\/p>\n\n\n\n<p>Existen muchos tipos de suplementos disponibles, y es importante elegir los que sean adecuados para ti. Por eso debes acudir siempre a un profesional que te asesore seg\u00fan tus necesidades individuales.<\/p>\n\n\n\n<p>En <a href=\"https:\/\/dev.lanierpharma.com\/en\/contacto\/\"><strong>Lanier Pharma<\/strong><\/a>, tu laboratorio farmac\u00e9utico de confianza, te ofrecemos una amplia gama de<strong> suplementos alimenticios de alta calidad <\/strong>para ayudarte a mejorar tu salud.<\/p>\n\n\n\n<p>Desde productos para el colesterol (<strong><a href=\"https:\/\/dev.lanierpharma.com\/en\/product\/laniercol\/\">Laniercol<\/a><\/strong>), hasta productos para tus defensas (<strong><a href=\"https:\/\/dev.lanierpharma.com\/en\/product\/inmunizat\/\">Inmunizat<\/a>, <a href=\"https:\/\/dev.lanierpharma.com\/en\/product\/inmunizat-infantil\/\">Inmunizat Infantil<\/a><\/strong>) o para tus articulaciones (<strong><a href=\"https:\/\/dev.lanierpharma.com\/en\/product\/artrinox\/\">Artrinox<\/a><\/strong>). Somos un laboratorio pionero por incluir en nuestros suplementos solo sustancias naturales que han probado su eficacia y seguridad mediante rigurosos estudios cient\u00edficos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es mejorar nuestra calidad de vida. Desde Lanier Pharma te vamos a dar algunos consejos para que cuidarte sea f\u00e1cil y placentero. El primer paso es establecer una rutina de h\u00e1bitos saludables Vete implementando los h\u00e1bitos saludables a tu [&hellip;]<\/p>\n","protected":false},"author":1291,"featured_media":4586,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[275],"tags":[531,216],"class_list":["post-4585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lanier-pharma","tag-calidad-de-vida","tag-suplementos-nutricionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida - Lanierpharma<\/title>\n<meta name=\"description\" content=\"Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es mejorar nuestra calidad de vida.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida - Lanierpharma\" \/>\n<meta property=\"og:description\" content=\"Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es mejorar nuestra calidad de vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.lanierpharma.com\/en\/tips-mejorar-calidad-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Lanierpharma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lanierpharma\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-24T09:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-28T16:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_Pharma-2-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:site\" content=\"@LanierPharma\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/\"},\"author\":{\"name\":\"redaccion\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/e0112d4efe5220eb883062a02bc83a7e\"},\"headline\":\"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida\",\"datePublished\":\"2024-01-24T09:06:00+00:00\",\"dateModified\":\"2025-12-28T16:09:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/\"},\"wordCount\":722,\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_Pharma-2-5.jpg\",\"keywords\":[\"calidad de vida\",\"suplementos nutricionales\"],\"articleSection\":[\"Lanier Pharma\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/\",\"name\":\"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida - Lanierpharma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_Pharma-2-5.jpg\",\"datePublished\":\"2024-01-24T09:06:00+00:00\",\"dateModified\":\"2025-12-28T16:09:17+00:00\",\"description\":\"Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es mejorar nuestra calidad de vida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_Pharma-2-5.jpg\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Lanier_Pharma-2-5.jpg\",\"width\":1279,\"height\":853,\"caption\":\"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/tips-mejorar-calidad-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#website\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"name\":\"Lanierpharma\",\"description\":\"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos\",\"publisher\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.lanierpharma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#organization\",\"name\":\"Lanierpharma\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"contentUrl\":\"https:\\\/\\\/dev.lanierpharma.com\\\/wp-content\\\/uploads\\\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png\",\"width\":567,\"height\":239,\"caption\":\"Lanierpharma\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lanierpharma\",\"https:\\\/\\\/x.com\\\/LanierPharma\",\"https:\\\/\\\/www.instagram.com\\\/lanier_pharma\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dev.lanierpharma.com\\\/#\\\/schema\\\/person\\\/e0112d4efe5220eb883062a02bc83a7e\",\"name\":\"redaccion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g\",\"caption\":\"redaccion\"},\"url\":\"https:\\\/\\\/dev.lanierpharma.com\\\/en\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida - Lanierpharma","description":"Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es mejorar nuestra calidad de vida.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida - Lanierpharma","og_description":"Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es mejorar nuestra calidad de vida.","og_url":"https:\/\/dev.lanierpharma.com\/en\/tips-mejorar-calidad-vida\/","og_site_name":"Lanierpharma","article_publisher":"https:\/\/www.facebook.com\/lanierpharma","article_published_time":"2024-01-24T09:06:00+00:00","article_modified_time":"2025-12-28T16:09:17+00:00","og_image":[{"width":1279,"height":853,"url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_Pharma-2-5.jpg","type":"image\/jpeg"}],"author":"redaccion","twitter_card":"summary_large_image","twitter_creator":"@LanierPharma","twitter_site":"@LanierPharma","twitter_misc":{"Written by":"redaccion","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/#article","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/"},"author":{"name":"redaccion","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/e0112d4efe5220eb883062a02bc83a7e"},"headline":"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida","datePublished":"2024-01-24T09:06:00+00:00","dateModified":"2025-12-28T16:09:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/"},"wordCount":722,"publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_Pharma-2-5.jpg","keywords":["calidad de vida","suplementos nutricionales"],"articleSection":["Lanier Pharma"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/","url":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/","name":"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida - Lanierpharma","isPartOf":{"@id":"https:\/\/dev.lanierpharma.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/#primaryimage"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_Pharma-2-5.jpg","datePublished":"2024-01-24T09:06:00+00:00","dateModified":"2025-12-28T16:09:17+00:00","description":"Indiscutiblemente, uno de los mejores prop\u00f3sitos que podemos tener para este a\u00f1o que acaba de comenzar es mejorar nuestra calidad de vida.","breadcrumb":{"@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/#primaryimage","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_Pharma-2-5.jpg","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Lanier_Pharma-2-5.jpg","width":1279,"height":853,"caption":"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.lanierpharma.com\/tips-mejorar-calidad-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dev.lanierpharma.com\/"},{"@type":"ListItem","position":2,"name":"Este 2024 elijo cuidarme: Tips generales para mejorar tu calidad de vida"}]},{"@type":"WebSite","@id":"https:\/\/dev.lanierpharma.com\/#website","url":"https:\/\/dev.lanierpharma.com\/","name":"Lanierpharma","description":"Empresa farmac\u00e9utica especializada en la investigaci\u00f3n, desarrollo y comercializaci\u00f3n de nutrac\u00e9uticos","publisher":{"@id":"https:\/\/dev.lanierpharma.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.lanierpharma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dev.lanierpharma.com\/#organization","name":"Lanierpharma","url":"https:\/\/dev.lanierpharma.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/","url":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","contentUrl":"https:\/\/dev.lanierpharma.com\/wp-content\/uploads\/Captura-de-pantalla-2025-06-30-a-las-10.13.35.png","width":567,"height":239,"caption":"Lanierpharma"},"image":{"@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lanierpharma","https:\/\/x.com\/LanierPharma","https:\/\/www.instagram.com\/lanier_pharma\/"]},{"@type":"Person","@id":"https:\/\/dev.lanierpharma.com\/#\/schema\/person\/e0112d4efe5220eb883062a02bc83a7e","name":"redaccion","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f3d585d9968e8b1a5541e5d31f5f962f121909617a0322a9ecc0a189ad8d2d5?s=96&d=mm&r=g","caption":"redaccion"},"url":"https:\/\/dev.lanierpharma.com\/en\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/4585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/users\/1291"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/comments?post=4585"}],"version-history":[{"count":1,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/4585\/revisions"}],"predecessor-version":[{"id":11644,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/posts\/4585\/revisions\/11644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media\/4586"}],"wp:attachment":[{"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/media?parent=4585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/categories?post=4585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.lanierpharma.com\/en\/wp-json\/wp\/v2\/tags?post=4585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}